{"id":26,"date":"2018-02-25T07:58:41","date_gmt":"2018-02-25T06:58:41","guid":{"rendered":"http:\/\/www.qm-wissen.de\/qm-lexikon\/?p=26"},"modified":"2018-02-25T08:57:36","modified_gmt":"2018-02-25T07:57:36","slug":"wahrscheinlichkeitsfunktion","status":"publish","type":"post","link":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wahrscheinlichkeitsfunktion\/","title":{"rendered":"Wahrscheinlichkeitsfktn."},"content":{"rendered":"<p>Die Wahrscheinlichkeitsfunktion f(x) stellt eine Verbindung zwischen einzelnen <a href=\"\/qm-lexikon\/diskrete-daten\/\">diskreten Daten<\/a> und der Wahrscheinlichkeit ihres Auftretens her (F\u00fcr <a href=\"\/qm-lexikon\/stetige-daten\/\">stetige Daten<\/a> \u00fcbernimmt dies die <a href=\"\/qm-lexikon\/dichtefunktion\/\">Dichtefunktion<\/a>).<\/p>\n<p>Formal: Gegeben sei eine diskrete (Zufalls-)Variable X. Die Funktion: f<sub>X<\/sub>(x<sub>i<\/sub>)=P(X=x<sub>i<\/sub>), die jedem x<sub>i<\/sub> die Wahrscheinlichkeit f<sub>X<\/sub>(x<sub>i<\/sub>) zuordnet, hei\u00dft Wahrscheinlichkeitsfunktion.<\/p>\n<p>Da mit Wahrscheinlichkeiten gearbeitet wird, gilt:<\/p>\n<ul>\n<li>Jedes f<sub>X<\/sub>(x<sub>i<\/sub>) kann nur Werte zwischen 0 und 1 annehmen.<\/li>\n<li>Die Summe \u00fcber alle f<sub>X<\/sub>(x<sub>i<\/sub>) = 1.<\/li>\n<\/ul>\n<p>Aussagen dar\u00fcber, mit welcher Wahrscheinlichkeit die Variable h\u00f6chstens eine bestimmte Auspr\u00e4gung erreicht, macht die zur Wahrscheinlichkeitsfunktion geh\u00f6rige <a href=\"\/qm-lexikon\/verteilungsfunktion\/\">Verteilungsfunktion<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Wahrscheinlichkeitsfunktion f(x) stellt eine Verbindung zwischen einzelnen diskreten Daten und der Wahrscheinlichkeit ihres Auftretens her (F\u00fcr stetige Daten \u00fcbernimmt<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[5],"_links":{"self":[{"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/posts\/26"}],"collection":[{"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":3,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"predecessor-version":[{"id":68,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/posts\/26\/revisions\/68"}],"wp:attachment":[{"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.qm-wissen.de\/qm-lexikon\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}